{"id":263,"count":16,"description":"<h3 data-pm-slice=\"1 1 []\">Descubre las joyas costeras y los puertos ocultos de Gran Breta\u00f1a<\/h3>\n<p data-pm-slice=\"1 1 []\">Emb\u00e1rcate en una aventura de navegaci\u00f3n a trav\u00e9s de las majestuosas aguas del Reino Unido. Desde los ic\u00f3nicos campos de navegaci\u00f3n de la costa sur hasta la belleza agreste del oeste de Escocia, estos viajes en velero son una combinaci\u00f3n \u00fanica de aventura, navegaci\u00f3n y exploraci\u00f3n. Navega frente a castillos hist\u00f3ricos, encantadores pueblos costeros y acantilados costeros impresionantes, todo mientras experimentas la emoci\u00f3n de navegar. Ya seas un marinero experimentado o nuevo en el tim\u00f3n, estas rutas combinan la elegancia brit\u00e1nica con una abundante historia, hermosos paisajes costeros y el esp\u00edritu de aventura. Lee nuestra gu\u00eda completa sobre vacaciones de navegaci\u00f3n en el Reino Unido aqu\u00ed.<\/p>","link":"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/","name":"Reino Unido &amp; Irlanda","slug":"reino-unido-irlanda","taxonomy":"product_cat","parent":236,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reino Unido &amp; Irlanda | Rubicon 3 Adventure<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reino Unido &amp; Irlanda | Rubicon 3 Adventure\" \/>\n<meta property=\"og:description\" content=\"Descubre las joyas costeras y los puertos ocultos de Gran Breta\u00f1a Emb\u00e1rcate en una aventura de navegaci\u00f3n a trav\u00e9s de las majestuosas aguas del Reino Unido. Desde los ic\u00f3nicos campos de navegaci\u00f3n de la costa sur hasta la belleza agreste del oeste de Escocia, estos viajes en velero son una combinaci\u00f3n \u00fanica de aventura, navegaci\u00f3n y exploraci\u00f3n. Navega frente a castillos hist\u00f3ricos, encantadores pueblos costeros y acantilados costeros impresionantes, todo mientras experimentas la emoci\u00f3n de navegar. Ya seas un marinero experimentado o nuevo en el tim\u00f3n, estas rutas combinan la elegancia brit\u00e1nica con una abundante historia, hermosos paisajes costeros y el esp\u00edritu de aventura. Lee nuestra gu\u00eda completa sobre vacaciones de navegaci\u00f3n en el Reino Unido aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/\" \/>\n<meta property=\"og:site_name\" content=\"Rubicon 3 Adventure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rubicon3adventure.com\/wp-content\/uploads\/2024\/03\/Rubicon_Schema-Image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@rubicon3sailing\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/categoria-producto\\\/vacaciones-de-aventura-en-velero\\\/reino-unido-irlanda\\\/\",\"url\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/categoria-producto\\\/vacaciones-de-aventura-en-velero\\\/reino-unido-irlanda\\\/\",\"name\":\"Reino Unido &amp; Irlanda | Rubicon 3 Adventure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#website\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/\",\"name\":\"Rubicon 3 Adventure\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#organization\",\"name\":\"Rubicon 3 Adventures\",\"alternateName\":\"Blueco Holdings Ltd\",\"url\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Rubicon_Schema-Image-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Rubicon_Schema-Image-scaled.jpg\",\"width\":2560,\"height\":1554,\"caption\":\"Rubicon 3 Adventures\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rubicon3adventure.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rubicon3sailing\",\"https:\\\/\\\/x.com\\\/rubicon3sailing\",\"https:\\\/\\\/www.instagram.com\\\/rubicon_3_sailing\\\/\",\"https:\\\/\\\/www.pinterest.co.uk\\\/rubicon3sailing\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUVTAy1Qm4lz0uZI_83Um8A\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rubicon-3\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reino Unido &amp; Irlanda | Rubicon 3 Adventure","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/","og_locale":"es_ES","og_type":"article","og_title":"Reino Unido &amp; Irlanda | Rubicon 3 Adventure","og_description":"Descubre las joyas costeras y los puertos ocultos de Gran Breta\u00f1a Emb\u00e1rcate en una aventura de navegaci\u00f3n a trav\u00e9s de las majestuosas aguas del Reino Unido. Desde los ic\u00f3nicos campos de navegaci\u00f3n de la costa sur hasta la belleza agreste del oeste de Escocia, estos viajes en velero son una combinaci\u00f3n \u00fanica de aventura, navegaci\u00f3n y exploraci\u00f3n. Navega frente a castillos hist\u00f3ricos, encantadores pueblos costeros y acantilados costeros impresionantes, todo mientras experimentas la emoci\u00f3n de navegar. Ya seas un marinero experimentado o nuevo en el tim\u00f3n, estas rutas combinan la elegancia brit\u00e1nica con una abundante historia, hermosos paisajes costeros y el esp\u00edritu de aventura. Lee nuestra gu\u00eda completa sobre vacaciones de navegaci\u00f3n en el Reino Unido aqu\u00ed.","og_url":"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/","og_site_name":"Rubicon 3 Adventure","og_image":[{"width":2560,"height":1554,"url":"https:\/\/www.rubicon3adventure.com\/wp-content\/uploads\/2024\/03\/Rubicon_Schema-Image-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@rubicon3sailing","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/","url":"https:\/\/www.rubicon3adventure.com\/es\/categoria-producto\/vacaciones-de-aventura-en-velero\/reino-unido-irlanda\/","name":"Reino Unido &amp; Irlanda | Rubicon 3 Adventure","isPartOf":{"@id":"https:\/\/www.rubicon3adventure.com\/es\/#website"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/www.rubicon3adventure.com\/es\/#website","url":"https:\/\/www.rubicon3adventure.com\/es\/","name":"Rubicon 3 Adventure","description":"","publisher":{"@id":"https:\/\/www.rubicon3adventure.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rubicon3adventure.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rubicon3adventure.com\/es\/#organization","name":"Rubicon 3 Adventures","alternateName":"Blueco Holdings Ltd","url":"https:\/\/www.rubicon3adventure.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rubicon3adventure.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rubicon3adventure.com\/wp-content\/uploads\/2024\/03\/Rubicon_Schema-Image-scaled.jpg","contentUrl":"https:\/\/www.rubicon3adventure.com\/wp-content\/uploads\/2024\/03\/Rubicon_Schema-Image-scaled.jpg","width":2560,"height":1554,"caption":"Rubicon 3 Adventures"},"image":{"@id":"https:\/\/www.rubicon3adventure.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rubicon3sailing","https:\/\/x.com\/rubicon3sailing","https:\/\/www.instagram.com\/rubicon_3_sailing\/","https:\/\/www.pinterest.co.uk\/rubicon3sailing\/","https:\/\/www.youtube.com\/channel\/UCUVTAy1Qm4lz0uZI_83Um8A","https:\/\/www.linkedin.com\/company\/rubicon-3\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.rubicon3adventure.com\/es\/wp-json\/wp\/v2\/product_cat\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rubicon3adventure.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.rubicon3adventure.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.rubicon3adventure.com\/es\/wp-json\/wp\/v2\/product_cat\/236"}],"wp:post_type":[{"href":"https:\/\/www.rubicon3adventure.com\/es\/wp-json\/wp\/v2\/product?product_cat=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}